{"id":16398,"date":"2018-02-02T11:56:07","date_gmt":"2018-02-02T15:56:07","guid":{"rendered":"http:\/\/blogdalucianaoliveira.com.br\/blog\/?p=16398"},"modified":"2018-02-02T11:56:07","modified_gmt":"2018-02-02T15:56:07","slug":"zarattini-diz-que-moro-subfaturou-compra-de-imovel-e-pede-investigacao","status":"publish","type":"post","link":"http:\/\/blogdalucianaoliveira.com.br\/blog\/2018\/02\/02\/zarattini-diz-que-moro-subfaturou-compra-de-imovel-e-pede-investigacao\/","title":{"rendered":"ZARATTINI DIZ QUE MORO SUBFATUROU COMPRA DE IM\u00d3VEL E PEDE INVESTIGA\u00c7\u00c3O"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"16399\" data-permalink=\"http:\/\/blogdalucianaoliveira.com.br\/blog\/2018\/02\/02\/zarattini-diz-que-moro-subfaturou-compra-de-imovel-e-pede-investigacao\/zara\/\" data-orig-file=\"https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2018\/02\/zara.jpg?fit=1000%2C357\" data-orig-size=\"1000,357\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"zara\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2018\/02\/zara.jpg?fit=300%2C107\" data-large-file=\"https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2018\/02\/zara.jpg?fit=600%2C214\" src=\"https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2018\/02\/zara.jpg?resize=600%2C214\" alt=\"zara\" width=\"600\" height=\"214\" class=\"alignnone size-full wp-image-16399\" srcset=\"https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2018\/02\/zara.jpg?w=1000 1000w, https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2018\/02\/zara.jpg?resize=300%2C107 300w, https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2018\/02\/zara.jpg?resize=768%2C274 768w, https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2018\/02\/zara.jpg?resize=800%2C286 800w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>247 &#8211; O deputado federal Carlos Zarattini (SP), que at\u00e9 recentemente era l\u00edder do PT, pediu ao procurador da Opera\u00e7\u00e3o Lava Jato Deltan Dallagnol que investigue a compra de um im\u00f3vel pelo juiz federal Sergio Moro, respons\u00e1vel pelos processos da opera\u00e7\u00e3o em primeira inst\u00e2ncia jur\u00eddica.<!--more--><\/p>\n<p>De acordo com o parlamentar, Moro declarou abaixo do valor de mercado, pois um im\u00f3vel de 256 metros quadrados \u00e9 muito mais caro do que R$ 170 mil. &#8220;Moro comprou um ap de 256m2 pelo pre\u00e7o de um Minha Casa Minha Vida faixa 2. Vamos investigar Dallagnol???&#8221;, questionou o parlamentar em sua conta no Twitter.<\/p>\n<p>A pol\u00eamica envolvendo o aux\u00edlio-moradia do magistrado veio ap\u00f3s uma mat\u00e9ria do jornal Folha de S. Paulo apontar que ele recebe R$ 4.378 deste benef\u00edcio, mas, com sal\u00e1rio-base de R$ 28.948, remunera\u00e7\u00e3o bruta dele chega a R$ 34.210, se somados os benef\u00edcios. Vale ressaltar que o valor est\u00e1 acima do teto constitucional do setor p\u00fablico, de R$ 33.763.<\/p>\n<p>Mas o curioso \u00e9 que, em determinados meses, o valor pode ser ainda maior. Em dezembro de 2017, por exemplo, o juiz ganhou R$ 6.838 em gratifica\u00e7\u00f5es, aumentando o sal\u00e1rio para R$ 41.047.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>247 &#8211; O deputado federal Carlos Zarattini (SP), que at\u00e9 recentemente era l\u00edder do PT, pediu ao procurador da Opera\u00e7\u00e3o Lava Jato Deltan Dallagnol que investigue a compra de um im\u00f3vel pelo juiz federal Sergio Moro, respons\u00e1vel pelos processos da opera\u00e7\u00e3o em primeira inst\u00e2ncia jur\u00eddica.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-16398","post","type-post","status-publish","format-standard","hentry","category-notas"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p7wKYW-4gu","jetpack-related-posts":[],"_links":{"self":[{"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/posts\/16398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/comments?post=16398"}],"version-history":[{"count":1,"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/posts\/16398\/revisions"}],"predecessor-version":[{"id":16400,"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/posts\/16398\/revisions\/16400"}],"wp:attachment":[{"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/media?parent=16398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/categories?post=16398"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/tags?post=16398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}