{"id":19423,"date":"2018-11-11T19:11:07","date_gmt":"2018-11-11T23:11:07","guid":{"rendered":"http:\/\/blogdalucianaoliveira.com.br\/blog\/?p=19423"},"modified":"2018-11-11T19:11:07","modified_gmt":"2018-11-11T23:11:07","slug":"atacado-por-bolsonaro-paulo-freire-recebe-homenagens-em-escolas-e-universidades-estrangeiras","status":"publish","type":"post","link":"http:\/\/blogdalucianaoliveira.com.br\/blog\/2018\/11\/11\/atacado-por-bolsonaro-paulo-freire-recebe-homenagens-em-escolas-e-universidades-estrangeiras\/","title":{"rendered":"Atacado por Bolsonaro, Paulo Freire recebe homenagens em escolas e universidades estrangeiras"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"19424\" data-permalink=\"http:\/\/blogdalucianaoliveira.com.br\/blog\/2018\/11\/11\/atacado-por-bolsonaro-paulo-freire-recebe-homenagens-em-escolas-e-universidades-estrangeiras\/6e023aab-84ac-4970-8e20-63c82a5de785\/\" data-orig-file=\"https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2018\/11\/6E023AAB-84AC-4970-8E20-63C82A5DE785.jpeg?fit=750%2C501\" data-orig-size=\"750,501\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"6E023AAB-84AC-4970-8E20-63C82A5DE785\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2018\/11\/6E023AAB-84AC-4970-8E20-63C82A5DE785.jpeg?fit=300%2C200\" data-large-file=\"https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2018\/11\/6E023AAB-84AC-4970-8E20-63C82A5DE785.jpeg?fit=600%2C401\" class=\"alignnone size-full wp-image-19424\" src=\"https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2018\/11\/6E023AAB-84AC-4970-8E20-63C82A5DE785.jpeg?resize=600%2C401\" alt=\"6E023AAB-84AC-4970-8E20-63C82A5DE785\" width=\"600\" height=\"401\" srcset=\"https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2018\/11\/6E023AAB-84AC-4970-8E20-63C82A5DE785.jpeg?w=750 750w, https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2018\/11\/6E023AAB-84AC-4970-8E20-63C82A5DE785.jpeg?resize=300%2C200 300w, https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2018\/11\/6E023AAB-84AC-4970-8E20-63C82A5DE785.jpeg?resize=449%2C300 449w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>No DCM &#8211; A Pedagogia do Oprimido \u00e9 o terceiro texto mais mais citado nas ci\u00eancias sociais e humanas, segundo levantamento de Elliot Green, da Escola de Economia de Londres. Pela sua import\u00e2ncia, a obra escrita durante o ex\u00edlio, no Chile, h\u00e1 50 anos, \u00e9 considerada pela Unesco como patrim\u00f4nio da humanidade.<!--more--><\/p>\n<p>A obra e seu autor, o educador brasileiro Paulo Freire, s\u00e3o reconhecidos no mundo inteiro, sendo ainda refer\u00eancias e objeto de estudo em diversas universidades.<\/p>\n<p>No Brasil, por\u00e9m, Freire tem sido execrado pelo presidente eleito Jair Bolsonaro (PSL) e seus seguidores. Tanto que em seu programa de governo ele se compromete a \u201cexpurgar a pedagogia de Paulo Freire\u201d.<\/p>\n<p>Mal sabe ele que escolas e universidades de diversos pa\u00edses se inspiram nas ideias do educador. Inclusive os Estados Unidos, t\u00e3o reverenciado por Bolsonaro, que chega ao ponto de bater contin\u00eancia diante da bandeira norte-americana.<\/p>\n<p><strong>Confira:<\/strong><\/p>\n<p><strong><span class=\"mrf-detailsMedia mrf-rDetailsMedia mrf-image mrf-horizontalImage\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"image-inline lazyloaded\" title=\"paulo freire unversity.jpg\" src=\"https:\/\/i0.wp.com\/www.redebrasilatual.com.br\/educacao\/2018\/11\/paulo-freire-e-homenageado-em-escolas-e-universidades-estrangeiras\/paulo-freire-unversity.jpg?w=600&#038;ssl=1\" alt=\"paulo freire unversity.jpg\" data-aspect-ratio=\"0.48\" data-height=\"378\" data-index=\"735\" data-src=\"https:\/\/www.redebrasilatual.com.br\/educacao\/2018\/11\/paulo-freire-e-homenageado-em-escolas-e-universidades-estrangeiras\/paulo-freire-unversity.jpg\" data-width=\"780\" data-originalsrc=\"data:image\/gif;base64,R0lGODlhAQABAAD\/ACwAAAAAAQABAAACADs%3D\" data-media-loaded=\"\" \/><\/span><\/strong><\/p>\n<p>Escola Livre Paulo Freire, Tucson, Arizona<\/p>\n<p><strong><span class=\"mrf-detailsMedia mrf-rDetailsMedia mrf-image mrf-horizontalImage\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"image-inline lazyloaded\" title=\"paulo freire inglaterra.jpg\" src=\"https:\/\/i0.wp.com\/www.redebrasilatual.com.br\/educacao\/2018\/11\/paulo-freire-e-homenageado-em-escolas-e-universidades-estrangeiras\/paulo-freire-inglaterra.jpg?w=600&#038;ssl=1\" alt=\"paulo freire inglaterra.jpg\" data-aspect-ratio=\"0.46\" data-height=\"361\" data-index=\"742\" data-src=\"https:\/\/www.redebrasilatual.com.br\/educacao\/2018\/11\/paulo-freire-e-homenageado-em-escolas-e-universidades-estrangeiras\/paulo-freire-inglaterra.jpg\" data-width=\"780\" data-originalsrc=\"data:image\/gif;base64,R0lGODlhAQABAAD\/ACwAAAAAAQABAAACADs%3D\" data-media-loaded=\"\" \/><\/span><\/strong><\/p>\n<p>Universidade de Lancashire Central, Lancashire, Reino Unido<\/p>\n<div class=\"mrf-adv mad mrf-preInsertedMad sRoba mrf-adv--all mrf-adv--0000 adSemiInvisible mrf-madLoaded mrf-madWidth-300 mrf-madHeight-250\" data-layout=\"inline_square_deeplinking_s\" data-loadstrategy=\"onScroll\" data-madtype=\"sRoba\" data-navigationlevel=\"1\" data-refreshfrequency=\"0\" data-sectionid=\"home\" data-virtualpageid=\"3\" data-madprocessed=\"true\" data-mrf-ssptargeting=\"marfeeltype\" data-mrf-madstyles=\"mrf-madWidth-300 mrf-madHeight-250\">\n<div id=\"mrf-6\" data-google-query-id=\"CM7g4rq6zd4CFcp_wQodkQMKpg\">\n<div id=\"google_ads_iframe_\/22571134\/crispr\/diariodocentrodomundo.com.br_2__container__\"><iframe loading=\"lazy\" id=\"google_ads_iframe_\/22571134\/crispr\/diariodocentrodomundo.com.br_2\" title=\"3rd party ad content\" src=\"https:\/\/tpc.googlesyndication.com\/safeframe\/1-0-30\/html\/container.html?v=1-0-31\" name=\"\" width=\"1\" height=\"1\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" sandbox=\"allow-forms allow-pointer-lock allow-popups allow-popups-to-escape-sandbox allow-same-origin allow-scripts allow-top-navigation-by-user-activation\" data-is-safeframe=\"true\" data-google-container-id=\"3\" data-load-complete=\"true\" data-mce-fragment=\"1\"><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><strong><span class=\"mrf-detailsMedia mrf-rDetailsMedia mrf-image mrf-horizontalImage\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"image-inline lazyloaded\" title=\"paulo freire up.jpg\" src=\"https:\/\/i0.wp.com\/www.redebrasilatual.com.br\/educacao\/2018\/11\/paulo-freire-e-homenageado-em-escolas-e-universidades-estrangeiras\/paulo-freire-up.jpg?w=600&#038;ssl=1\" alt=\"paulo freire up.jpg\" data-aspect-ratio=\"0.44\" data-height=\"343\" data-index=\"749\" data-src=\"https:\/\/www.redebrasilatual.com.br\/educacao\/2018\/11\/paulo-freire-e-homenageado-em-escolas-e-universidades-estrangeiras\/paulo-freire-up.jpg\" data-width=\"780\" data-originalsrc=\"data:image\/gif;base64,R0lGODlhAQABAAD\/ACwAAAAAAQABAAACADs%3D\" data-media-loaded=\"\" \/><\/span><\/strong><\/p>\n<p>Universidade do Porto, Porto, Portugal<\/p>\n<p><strong><span class=\"mrf-detailsMedia mrf-rDetailsMedia mrf-image mrf-horizontalImage\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"image-inline lazyloaded\" title=\"paulo freire austria.jpg\" src=\"https:\/\/i0.wp.com\/www.redebrasilatual.com.br\/educacao\/2018\/11\/paulo-freire-e-homenageado-em-escolas-e-universidades-estrangeiras\/paulo-freire-austria.jpg?w=600&#038;ssl=1\" alt=\"paulo freire austria.jpg\" data-aspect-ratio=\"0.37\" data-height=\"287\" data-index=\"756\" data-src=\"https:\/\/www.redebrasilatual.com.br\/educacao\/2018\/11\/paulo-freire-e-homenageado-em-escolas-e-universidades-estrangeiras\/paulo-freire-austria.jpg\" data-width=\"780\" data-originalsrc=\"data:image\/gif;base64,R0lGODlhAQABAAD\/ACwAAAAAAQABAAACADs%3D\" data-media-loaded=\"\" \/><\/span><\/strong><\/p>\n<p>Centro Paulo Freire, Viena, \u00c1ustria<\/p>\n<p><strong><span class=\"mrf-detailsMedia mrf-rDetailsMedia mrf-image\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"image-inline lazyloaded\" title=\"paulo freire alemanha.jpg\" src=\"https:\/\/i0.wp.com\/www.redebrasilatual.com.br\/educacao\/2018\/11\/paulo-freire-e-homenageado-em-escolas-e-universidades-estrangeiras\/paulo-freire-alemanha.jpg?w=600&#038;ssl=1\" alt=\"paulo freire alemanha.jpg\" data-aspect-ratio=\"0.60\" data-height=\"470\" data-index=\"763\" data-src=\"https:\/\/www.redebrasilatual.com.br\/educacao\/2018\/11\/paulo-freire-e-homenageado-em-escolas-e-universidades-estrangeiras\/paulo-freire-alemanha.jpg\" data-width=\"780\" data-originalsrc=\"data:image\/gif;base64,R0lGODlhAQABAAD\/ACwAAAAAAQABAAACADs%3D\" data-media-loaded=\"\" \/><\/span><\/strong><\/p>\n<p>Coopera\u00e7\u00e3o Paulo Freire,\u00a0Bad D\u00fcrkheim, Alemanha<\/p>\n<div class=\"mrf-adv mad mrf-preInsertedMad sRoba mrf-adv--all mrf-adv--0000 adSemiInvisible mrf-madLoaded mrf-madWidth-300 mrf-madHeight-600\" data-layout=\"inline_square_deeplinking_s\" data-loadstrategy=\"onScroll\" data-madtype=\"sRoba\" data-navigationlevel=\"1\" data-refreshfrequency=\"0\" data-sectionid=\"home\" data-virtualpageid=\"4\" data-madprocessed=\"true\" data-mrf-ssptargeting=\"marfeeltype\" data-mrf-madstyles=\"mrf-madWidth-300 mrf-madHeight-600\">\n<div id=\"mrf-7\" data-google-query-id=\"CJT36cK6zd4CFRN2wQodaesE5A\">\n<div id=\"google_ads_iframe_\/22571134\/crispr\/diariodocentrodomundo.com.br_3__container__\"><iframe loading=\"lazy\" id=\"google_ads_iframe_\/22571134\/crispr\/diariodocentrodomundo.com.br_3\" title=\"3rd party ad content\" src=\"https:\/\/tpc.googlesyndication.com\/safeframe\/1-0-30\/html\/container.html?v=1-0-31\" name=\"\" width=\"1\" height=\"1\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" sandbox=\"allow-forms allow-pointer-lock allow-popups allow-popups-to-escape-sandbox allow-same-origin allow-scripts allow-top-navigation-by-user-activation\" data-is-safeframe=\"true\" data-google-container-id=\"4\" data-load-complete=\"true\" data-mce-fragment=\"1\"><\/iframe><\/div>\n<\/div>\n<\/div>\n<p>Universidade Paulo Freire, Man\u00e1gua, Nicar\u00e1gua<\/p>\n<p><span class=\"mrf-detailsMedia mrf-rDetailsMedia mrf-image mrf-horizontalImage\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"image-inline lazyloaded\" title=\"paulo freire estados unidos.jpg\" src=\"https:\/\/i0.wp.com\/www.redebrasilatual.com.br\/educacao\/2018\/11\/paulo-freire-e-homenageado-em-escolas-e-universidades-estrangeiras\/paulo-freire-estados-unidos.jpg?w=600&#038;ssl=1\" alt=\"paulo freire estados unidos.jpg\" data-aspect-ratio=\"0.44\" data-height=\"344\" data-index=\"772\" data-src=\"https:\/\/www.redebrasilatual.com.br\/educacao\/2018\/11\/paulo-freire-e-homenageado-em-escolas-e-universidades-estrangeiras\/paulo-freire-estados-unidos.jpg\" data-width=\"780\" data-originalsrc=\"data:image\/gif;base64,R0lGODlhAQABAAD\/ACwAAAAAAQABAAACADs%3D\" data-media-loaded=\"\" \/><\/span><\/p>\n<p>Universidade Chapman, Calif\u00f3rnia, Estados Unidos<\/p>\n<p><span class=\"mrf-detailsMedia mrf-rDetailsMedia mrf-image mrf-horizontalImage\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"image-inline lazyloaded\" title=\"paulo freire finlandia.jpg\" src=\"https:\/\/i0.wp.com\/www.redebrasilatual.com.br\/educacao\/2018\/11\/paulo-freire-e-homenageado-em-escolas-e-universidades-estrangeiras\/paulo-freire-finlandia.jpg?w=600&#038;ssl=1\" alt=\"paulo freire finlandia.jpg\" data-aspect-ratio=\"0.48\" data-height=\"374\" data-index=\"778\" data-src=\"https:\/\/www.redebrasilatual.com.br\/educacao\/2018\/11\/paulo-freire-e-homenageado-em-escolas-e-universidades-estrangeiras\/paulo-freire-finlandia.jpg\" data-width=\"780\" data-originalsrc=\"data:image\/gif;base64,R0lGODlhAQABAAD\/ACwAAAAAAQABAAACADs%3D\" data-media-loaded=\"\" \/><\/span><\/p>\n<p>Centro Paulo Freire, Finl\u00e2ndia<\/p>\n<p><span class=\"mrf-detailsMedia mrf-rDetailsMedia mrf-image mrf-horizontalImage\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"image-inline lazyloaded\" title=\"paulo freire africa.jpg\" src=\"https:\/\/i0.wp.com\/www.redebrasilatual.com.br\/educacao\/2018\/11\/paulo-freire-e-homenageado-em-escolas-e-universidades-estrangeiras\/paulo-freire-africa.jpg?w=600&#038;ssl=1\" alt=\"paulo freire africa.jpg\" data-aspect-ratio=\"0.58\" data-height=\"451\" data-index=\"784\" data-src=\"https:\/\/www.redebrasilatual.com.br\/educacao\/2018\/11\/paulo-freire-e-homenageado-em-escolas-e-universidades-estrangeiras\/paulo-freire-africa.jpg\" data-width=\"780\" data-originalsrc=\"data:image\/gif;base64,R0lGODlhAQABAAD\/ACwAAAAAAQABAAACADs%3D\" data-media-loaded=\"\" \/><\/span><\/p>\n<p>Universidade de KwaZulu, \u00c1frica do Sul<\/p>\n<div class=\"mrf-adv mad mrf-preInsertedMad sRoba\" data-layout=\"inline_square_deeplinking_s\" data-loadstrategy=\"onScroll\" data-madtype=\"sRoba\" data-navigationlevel=\"1\" data-refreshfrequency=\"0\" data-sectionid=\"home\" data-virtualpageid=\"5\" data-madprocessed=\"true\" data-mrf-ssptargeting=\"marfeeltype\" data-emptymad=\"true\"><\/div>\n<div id=\"execphp-4\" class=\"td_block_template_1 widget widget_execphp\">\n<div class=\"execphpwidget\">\n<div class=\"acompanhe-face\"><strong><em>.<\/em><\/strong><\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>No DCM &#8211; A Pedagogia do Oprimido \u00e9 o terceiro texto mais mais citado nas ci\u00eancias sociais e humanas, segundo levantamento de Elliot Green, da Escola de Economia de Londres. Pela sua import\u00e2ncia, a obra escrita durante o ex\u00edlio, no Chile, h\u00e1 50 anos, \u00e9 considerada pela Unesco como patrim\u00f4nio da humanidade.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-19423","post","type-post","status-publish","format-standard","hentry","category-notas"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p7wKYW-53h","jetpack-related-posts":[],"_links":{"self":[{"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/posts\/19423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/comments?post=19423"}],"version-history":[{"count":1,"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/posts\/19423\/revisions"}],"predecessor-version":[{"id":19425,"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/posts\/19423\/revisions\/19425"}],"wp:attachment":[{"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/media?parent=19423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/categories?post=19423"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/tags?post=19423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}