{"id":19426,"date":"2018-11-11T20:50:07","date_gmt":"2018-11-12T00:50:07","guid":{"rendered":"http:\/\/blogdalucianaoliveira.com.br\/blog\/?p=19426"},"modified":"2018-11-11T20:50:07","modified_gmt":"2018-11-12T00:50:07","slug":"nos-100-anos-do-fim-da-1a-guerra-lideres-veem-em-nacionalismo-ameaca-a-paz","status":"publish","type":"post","link":"http:\/\/blogdalucianaoliveira.com.br\/blog\/2018\/11\/11\/nos-100-anos-do-fim-da-1a-guerra-lideres-veem-em-nacionalismo-ameaca-a-paz\/","title":{"rendered":"Nos 100 anos do fim da 1\u00aa Guerra, l\u00edderes veem em nacionalismo amea\u00e7a \u00e0 paz"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"19427\" data-permalink=\"http:\/\/blogdalucianaoliveira.com.br\/blog\/2018\/11\/11\/nos-100-anos-do-fim-da-1a-guerra-lideres-veem-em-nacionalismo-ameaca-a-paz\/e3ce7546-4e06-4647-99a9-6833a41d9f4d\/\" data-orig-file=\"https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2018\/11\/E3CE7546-4E06-4647-99A9-6833A41D9F4D.jpeg?fit=768%2C512\" data-orig-size=\"768,512\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"E3CE7546-4E06-4647-99A9-6833A41D9F4D\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2018\/11\/E3CE7546-4E06-4647-99A9-6833A41D9F4D.jpeg?fit=300%2C200\" data-large-file=\"https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2018\/11\/E3CE7546-4E06-4647-99A9-6833A41D9F4D.jpeg?fit=600%2C400\" class=\"alignnone size-full wp-image-19427\" src=\"https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2018\/11\/E3CE7546-4E06-4647-99A9-6833A41D9F4D.jpeg?resize=600%2C400\" alt=\"E3CE7546-4E06-4647-99A9-6833A41D9F4D\" width=\"600\" height=\"400\" srcset=\"https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2018\/11\/E3CE7546-4E06-4647-99A9-6833A41D9F4D.jpeg?w=768 768w, https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2018\/11\/E3CE7546-4E06-4647-99A9-6833A41D9F4D.jpeg?resize=300%2C200 300w, https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2018\/11\/E3CE7546-4E06-4647-99A9-6833A41D9F4D.jpeg?resize=450%2C300 450w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>Discurso de Macron mira Trump e governos de ultradireita na Pol\u00f4nia e na Hungria<!--more--><\/p>\n<p>Lucas Neves<br \/>\nPARIS<br \/>\nO presidente da Fran\u00e7a, Emmanuel Macron, usou neste domingo (11) a cerim\u00f4nia do centen\u00e1rio do Armist\u00edcio da Primeira Guerra (1914-18) para uma defesa enf\u00e1tica da coopera\u00e7\u00e3o internacional e do multilateralismo.<\/p>\n<p>O discurso foi, sobretudo, endere\u00e7ado ao l\u00edder americano Donald Trump e a pa\u00edses europeus como Hungria e Pol\u00f4nia, em que o populismo nacionalista ganha for\u00e7a.<\/p>\n<p>No ato, realizado sob o Arco do Triunfo, onde fica o Monumento ao Soldado Desconhecido em Paris, Macron disse que &#8220;cem anos depois, a cicatriz [da guerra] ainda \u00e9 vis\u00edvel na face do mundo&#8221; e exortou governantes a n\u00e3o confundir patriotismo e nacionalismo \u2014o segundo seria a trai\u00e7\u00e3o do primeiro.<\/p>\n<p>&#8220;Ao dizer &#8216;nossos interesses primeiro, os outros pouco importam&#8217;, apaga-se aquilo que uma na\u00e7\u00e3o tem de mais precioso [&#8230;], aquilo que a leva a ser grande: seus valores morais&#8221;, afirmou, diante de uma plateia de 72 chefes de governo e de Estado, dentre os quais o Trump de slogans como &#8220;A Am\u00e9rica em primeiro lugar&#8221; e &#8220;Fa\u00e7a a Am\u00e9rica voltar a ser grande&#8221;.<\/p>\n<p>Ele lembrou que as primeiras parcerias internacionais remontam ao fim da Grande Guerra e, encadeando express\u00f5es como &#8220;amizade entre os povos&#8221; e &#8220;esp\u00edrito de concilia\u00e7\u00e3o&#8221;, insistiu em quanto essas no\u00e7\u00f5es conduziram \u00e0 aproxima\u00e7\u00e3o entre Fran\u00e7a e Alemanha (advers\u00e1rias no front de 1914 a 1918) e \u00e0 cria\u00e7\u00e3o da Uni\u00e3o Europeia e da Organiza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas (ONU).<\/p>\n<p>&#8220;A hist\u00f3ria amea\u00e7a \u00e0s vezes retomar seu curso tr\u00e1gico e comprometer nosso legado de paz&#8221;, disse.<\/p>\n<p>&#8220;Somemos nossas esperan\u00e7as em vez de colocar em confronto nossos medos. Juntos, podemos afastar essas amea\u00e7as que s\u00e3o o espectro do aquecimento global, a pobreza, a fome, as desigualdades, a ignor\u00e2ncia.&#8221;<\/p>\n<p>Era mais um aceno a Trump, que em 2017 retirou os EUA do Acordo de Paris (2015), com o qual 196 pa\u00edses se comprometeram a combater a mudan\u00e7a clim\u00e1tica e tentar frear o aquecimento do planeta.<\/p>\n<p>A cerim\u00f4nia foi coreografada para dar protagonismo a Macron (\u00fanico a discursar, ele passou as tropas em revista longa e solitariamente) e retrat\u00e1-lo como l\u00edder nato do globalismo (em oposi\u00e7\u00e3o \u00e0 insularidade e ao nativismo).<\/p>\n<p>Al\u00e9m de Trump, estavam na plateia a chanceler alem\u00e3, Angela Merkel, os presidentes russo, Vladimir Putin, e turco, Recep Tayyip Erdogan, e o premi\u00ea espanhol, Pedro S\u00e1nchez, entre outros. A chefe de governo brit\u00e2nica, Theresa May, ficou no Reino Unido para acompanhar celebra\u00e7\u00f5es locais.<\/p>\n<p>\u00c0 tarde, na abertura do F\u00f3rum sobre a Paz, criado pelo governo franc\u00eas para abrigar debates sobre governan\u00e7a global, Merkel declarou estar inquieta com o fato de que &#8220;se volte a agir como se fosse poss\u00edvel pura e simplesmente ignorar nossos compromissos rec\u00edprocos&#8221;.<\/p>\n<p>Segundo ela, &#8220;o equil\u00edbrio pac\u00edfico entre os interesses de uns e de outros e mesmo o projeto europeu de paz est\u00e3o sendo colocados em quest\u00e3o&#8221;.<\/p>\n<p>Trump n\u00e3o compareceu. Preferiu visitar um cemit\u00e9rio militar americano na periferia de Paris.<br \/>\nN\u00e3o foi a primeira desfeita com o anfitri\u00e3o. <\/p>\n<p>No s\u00e1bado, Trump evitara um dos atos previstos, culpando a chuva. Na sexta (9), ao pousar na capital francesa, o americano escrevera em uma rede social que tinha se sentido insultado pela declara\u00e7\u00e3o de Macron, em entrevista pr\u00e9via, de que a Europa deveria criar um Ex\u00e9rcito conjunto para se defender &#8220;de China, R\u00fassia e at\u00e9 dos EUA&#8221;.<\/p>\n<p>&#8220;Mas talvez a Europa devesse antes desembolsar uma quantia mais justa para a [manuten\u00e7\u00e3o da] Otan, que os Estados Unidos bancam amplamente&#8221;, completou Trump.<\/p>\n<p>O franc\u00eas n\u00e3o se fez de rogado. Em entrevista \u00e0 rede americana CNN exibida no domingo (11), afirmou preferir &#8220;discuss\u00f5es cara a cara ou responder a quest\u00f5es&#8221; a &#8220;fazer diplomacia por tu\u00edtes&#8221;.<\/p>\n<p>Apesar da alfinetada, por\u00e9m, o presidente franc\u00eas disse concordar com o republicano sobre a necessidade de a Europa incrementar sua participa\u00e7\u00e3o no custeio da Otan.<\/p>\n<p>&#8220;N\u00e3o quero que os pa\u00edses europeus aumentem seus or\u00e7amentos de defesa para comprar armas ou material americano, mas sim para refor\u00e7ar sua autonomia&#8221;, ressalvou.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Discurso de Macron mira Trump e governos de ultradireita na Pol\u00f4nia e na Hungria<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-19426","post","type-post","status-publish","format-standard","hentry","category-notas"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p7wKYW-53k","jetpack-related-posts":[],"_links":{"self":[{"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/posts\/19426","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/comments?post=19426"}],"version-history":[{"count":1,"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/posts\/19426\/revisions"}],"predecessor-version":[{"id":19428,"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/posts\/19426\/revisions\/19428"}],"wp:attachment":[{"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/media?parent=19426"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/categories?post=19426"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/tags?post=19426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}