{"id":19568,"date":"2018-11-23T13:25:24","date_gmt":"2018-11-23T17:25:24","guid":{"rendered":"http:\/\/blogdalucianaoliveira.com.br\/blog\/?p=19568"},"modified":"2018-11-23T13:25:24","modified_gmt":"2018-11-23T17:25:24","slug":"expectativa-e-a-realidade-que-vem-por-ai","status":"publish","type":"post","link":"http:\/\/blogdalucianaoliveira.com.br\/blog\/2018\/11\/23\/expectativa-e-a-realidade-que-vem-por-ai\/","title":{"rendered":"Expectativa e a realidade que vem por a\u00ed."},"content":{"rendered":"<p><del><\/del><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"19569\" data-permalink=\"http:\/\/blogdalucianaoliveira.com.br\/blog\/2018\/11\/23\/expectativa-e-a-realidade-que-vem-por-ai\/f5c18e92-4efc-4512-8b38-2006e119b41f\/\" data-orig-file=\"https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2018\/11\/F5C18E92-4EFC-4512-8B38-2006E119B41F.jpeg?fit=656%2C656\" data-orig-size=\"656,656\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"F5C18E92-4EFC-4512-8B38-2006E119B41F\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2018\/11\/F5C18E92-4EFC-4512-8B38-2006E119B41F.jpeg?fit=300%2C300\" data-large-file=\"https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2018\/11\/F5C18E92-4EFC-4512-8B38-2006E119B41F.jpeg?fit=600%2C600\" class=\"alignnone size-full wp-image-19569\" src=\"https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2018\/11\/F5C18E92-4EFC-4512-8B38-2006E119B41F.jpeg?resize=600%2C600\" alt=\"F5C18E92-4EFC-4512-8B38-2006E119B41F\" width=\"600\" height=\"600\" srcset=\"https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2018\/11\/F5C18E92-4EFC-4512-8B38-2006E119B41F.jpeg?w=656 656w, https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2018\/11\/F5C18E92-4EFC-4512-8B38-2006E119B41F.jpeg?resize=150%2C150 150w, https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2018\/11\/F5C18E92-4EFC-4512-8B38-2006E119B41F.jpeg?resize=300%2C300 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-19568","post","type-post","status-publish","format-standard","hentry","category-notas"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p7wKYW-55C","jetpack-related-posts":[],"_links":{"self":[{"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/posts\/19568","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/comments?post=19568"}],"version-history":[{"count":1,"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/posts\/19568\/revisions"}],"predecessor-version":[{"id":19570,"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/posts\/19568\/revisions\/19570"}],"wp:attachment":[{"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/media?parent=19568"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/categories?post=19568"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/tags?post=19568"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}