{"id":20023,"date":"2019-01-11T16:54:22","date_gmt":"2019-01-11T20:54:22","guid":{"rendered":"http:\/\/blogdalucianaoliveira.com.br\/blog\/?p=20023"},"modified":"2019-01-11T16:54:22","modified_gmt":"2019-01-11T20:54:22","slug":"nao-ha-metodo-na-burrice","status":"publish","type":"post","link":"http:\/\/blogdalucianaoliveira.com.br\/blog\/2019\/01\/11\/nao-ha-metodo-na-burrice\/","title":{"rendered":"N\u00e3o h\u00e1 m\u00e9todo na burrice"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"20024\" data-permalink=\"http:\/\/blogdalucianaoliveira.com.br\/blog\/2019\/01\/11\/nao-ha-metodo-na-burrice\/a0118aeb-2fc0-4fec-b22d-4a0e292f0110\/\" data-orig-file=\"https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2019\/01\/A0118AEB-2FC0-4FEC-B22D-4A0E292F0110.jpeg?fit=750%2C429\" data-orig-size=\"750,429\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"A0118AEB-2FC0-4FEC-B22D-4A0E292F0110\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2019\/01\/A0118AEB-2FC0-4FEC-B22D-4A0E292F0110.jpeg?fit=300%2C172\" data-large-file=\"https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2019\/01\/A0118AEB-2FC0-4FEC-B22D-4A0E292F0110.jpeg?fit=600%2C343\" src=\"https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2019\/01\/A0118AEB-2FC0-4FEC-B22D-4A0E292F0110.jpeg?resize=600%2C343\" alt=\"A0118AEB-2FC0-4FEC-B22D-4A0E292F0110\" width=\"600\" height=\"343\" class=\"alignnone size-full wp-image-20024\" srcset=\"https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2019\/01\/A0118AEB-2FC0-4FEC-B22D-4A0E292F0110.jpeg?w=750 750w, https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2019\/01\/A0118AEB-2FC0-4FEC-B22D-4A0E292F0110.jpeg?resize=300%2C172 300w, https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2019\/01\/A0118AEB-2FC0-4FEC-B22D-4A0E292F0110.jpeg?resize=524%2C300 524w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>O grande Goethe j\u00e1 nos advertia que \u201cn\u00e3o h\u00e1 nada mais terr\u00edvel que uma ignor\u00e2ncia ativa\u201d (Es ist nichts schreklicher als eine t\u00e4tige Unwissenheit). <!--more--><\/p>\n<p>Por Marcelo Zero<\/p>\n<p>Obviamente, Goethe n\u00e3o teve o prazer de conhecer Bolsonaro e sua preclara equipe de fundamentalistas crist\u00e3os e sumidades emergidas das redes sociais. Se tivesse, teria acrescentado que n\u00e3o h\u00e1 nada mais desastroso que a ignor\u00e2ncia ativa que chega ao poder. <\/p>\n<p>Com efeito, mal come\u00e7ou e o governo do capit\u00e3o exibe a um mundo estarrecido um festival tragic\u00f4mico de declara\u00e7\u00f5es brutais e estapaf\u00fardias e de decis\u00f5es be\u00f3cias e cretinas, seguidas invariavelmente por apressados e canhestros desmentidos. Ornamenta esse festival de obtusidades as seguidas desautoriza\u00e7\u00f5es dos zurros presidenciais.<br \/>\nCom o novo mandato, instaurou-se a mais completa anomia.  <\/p>\n<p>Ningu\u00e9m sabe direito que decis\u00f5es ser\u00e3o concretizadas e quem, de fato, manda no governo, s\u00e9 \u00e9 que h\u00e1 algu\u00e9m que manda. H\u00e1 a inc\u00f4moda sensa\u00e7\u00e3o de se estar em num barco \u00e0 deriva, que ruma impotente rumo ao Maelstrom, sob o olhar impass\u00edvel do Jesus da Goiabeira, que n\u00e3o ora por n\u00f3s.<br \/>\nH\u00e1 alguns, no entanto, que veem essa algazarra tr\u00e1gica como um plano mefistof\u00e9lico, destinado a distrair a opini\u00e3o p\u00fablica das \u201cverdadeiras inten\u00e7\u00f5es\u201d do governo fascistoide, que quer entregar os destinos da Na\u00e7\u00e3o a desinteressados agentes do capital internacional.<\/p>\n<p>\u00c9 poss\u00edvel. Afinal, nada mais funcional a esses interesses que um presidente que fez da ignor\u00e2ncia e da bo\u00e7alidade a sua raison d\u2019\u00eatre. Um presidente que n\u00e3o entende nada, n\u00e3o manda nada, e que est\u00e1 disposto a bater contin\u00eancia at\u00e9 para o Rin Tin Tin, pastor alem\u00e3o que serve galhardamente ao Ex\u00e9rcito dos EUA.<br \/>\nComo diziam os antigos gregos, aqueles a quem os deuses querem destruir primeiro enlouquecem. Portanto, \u00e9 poss\u00edvel que haja alguma funcionalidade oculta, bem oculta, nesse enredo giocoso de opera bufa. Alguma coisa cuja l\u00f3gica seja acess\u00edvel apenas aos deuses.<\/p>\n<p>Suspeito, contudo, usando a Navalha de Occam, que a verdade seja, como soe acontecer, mais simples e mais brutal: o Brasil foi assaltado por uma legi\u00e3o de oligofr\u00eanicos que n\u00e3o t\u00eam a menor ideia de como governar o pa\u00eds.<br \/>\nMesmo o insigne \u201cPosto Ipiranga\u201d, sumidade gestada na Escola de Chicago, que respirou os ares impolutos de Santiago de Chile, parece desconhecer fatos b\u00e1sicos sobre o Brasil, como, por exemplo, o de que o or\u00e7amento de um ano tem de ser aprovado no ano anterior, informa\u00e7\u00e3o acess\u00edvel at\u00e9 mesmo a mortais comuns medianamente letrados.<\/p>\n<p>O Itamaraty, que j\u00e1 nos legou quadros extraordin\u00e1rios, \u00e0 esquerda e \u00e0 direita,  agora nos brinda Ernesto Ara\u00fajo, um diplomata, por assim dizer, intelectualmente muito original, at\u00e9 mesmo surpreendente. Suas animadas arengas demonstram, em v\u00e1rios idiomas, uma mente muito atr\u00e1s de seu tempo.<br \/>\nJ\u00e1 o grande c\u00edrculo militar do poder parece ter faltado a algumas aulas na Escola Superior de Guerra e n\u00e3o ter se empenhado muito na leitura das obras de Golbery. Israel so explicaria as misteriosas refer\u00eancias \u00e0 Terceira Guerra Mundial, provavelmente desencadeada contra o kit gay, aliado da mamadeira de piroca, bem como a total aus\u00eancia de rigor geopol\u00edtico em suas soi disant \u201can\u00e1lises\u201d. <\/p>\n<p>N\u00e3o creio que haja funcionalidade pol\u00edtica nessa grotesca barafunda.  Qualquer governo, mesmo aquele que n\u00e3o tem compromisso com os interesses do pa\u00eds e do seu povo, precisa de credibilidade e legitimidade para administrar.<br \/>\nNo entanto, o desgoverno do capit\u00e3o parece obstinadamente empenhado em queimar rapidamente todo o seu capital pol\u00edtico, laboriosamente amealhado em anos de fake news e de \u00f3dio a tudo que cheire a progresso.<\/p>\n<p>Muito provavelmente, a legi\u00e3o de ac\u00e9falos que se apossou do Estado achava que governar seria t\u00e3o f\u00e1cil quanto disseminar mentiras pelo Twitter e pelo Facebook, ou como operar \u201cmilagres\u201d numa igreja neopentecostal. <\/p>\n<p>Infelizmente, n\u00e3o \u00e9. Governar exige profundo conhecimento do pa\u00eds, do mundo e da m\u00e1quina p\u00fablica. \u00c9 tarefa muito complexa e dif\u00edcil, que deveria ser atribu\u00edda, segundo Plat\u00e3o, apenas a homens s\u00e1bios. Sabedoria que n\u00e3o pode ser identificada com conhecimento acad\u00eamico, mas que n\u00e3o pode dispensar vis\u00e3o racional do mundo, coisa que o capit\u00e3o e sua voluntarista armada Bolsoleone evidentemente n\u00e3o t\u00eam.  <\/p>\n<p>No governo, f\u00e9 n\u00e3o move montanhas. Compet\u00eancia, sim.<br \/>\nAssim sendo, n\u00e3o parece haver m\u00e9todo na burrice e plano na improvisa\u00e7\u00e3o.<br \/>\nConta a hist\u00f3ria que Leon Trotsky, exasperado com as posi\u00e7\u00f5es irrefletidas do escritor e pol\u00edtico norte-americano Dwight Macdonald, teria afirmado: \u201cTodo homem tem o direito de ser ocasionalmente est\u00fapido, mas o companheiro Macdonald abusa desse privil\u00e9gio\u201d.<\/p>\n<p>Como Goethe, Trotsky n\u00e3o conheceu Bolsonaro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O grande Goethe j\u00e1 nos advertia que \u201cn\u00e3o h\u00e1 nada mais terr\u00edvel que uma ignor\u00e2ncia ativa\u201d (Es ist nichts schreklicher als eine t\u00e4tige Unwissenheit).<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-20023","post","type-post","status-publish","format-standard","hentry","category-notas"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p7wKYW-5cX","jetpack-related-posts":[],"_links":{"self":[{"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/posts\/20023","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/comments?post=20023"}],"version-history":[{"count":1,"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/posts\/20023\/revisions"}],"predecessor-version":[{"id":20025,"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/posts\/20023\/revisions\/20025"}],"wp:attachment":[{"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/media?parent=20023"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/categories?post=20023"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/tags?post=20023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}