{"id":39206,"date":"2026-07-14T20:05:40","date_gmt":"2026-07-15T00:05:40","guid":{"rendered":"https:\/\/blogdalucianaoliveira.com.br\/blog\/?p=39206"},"modified":"2026-07-14T20:05:40","modified_gmt":"2026-07-15T00:05:40","slug":"xi-jinping-participara-da-conferencia-mundial-de-ia-2026","status":"publish","type":"post","link":"http:\/\/blogdalucianaoliveira.com.br\/blog\/2026\/07\/14\/xi-jinping-participara-da-conferencia-mundial-de-ia-2026\/","title":{"rendered":"Xi Jinping participar\u00e1 da Confer\u00eancia Mundial de IA 2026"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"39207\" data-permalink=\"http:\/\/blogdalucianaoliveira.com.br\/blog\/2026\/07\/14\/xi-jinping-participara-da-conferencia-mundial-de-ia-2026\/img_1327\/\" data-orig-file=\"https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2026\/07\/IMG_1327.jpeg?fit=1080%2C608\" data-orig-size=\"1080,608\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;,&quot;alt&quot;:&quot;&quot;}\" data-image-title=\"IMG_1327\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2026\/07\/IMG_1327.jpeg?fit=300%2C169\" data-large-file=\"https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2026\/07\/IMG_1327.jpeg?fit=600%2C338\" class=\"size-medium wp-image-39207 aligncenter\" src=\"https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2026\/07\/IMG_1327.jpeg?resize=300%2C169\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2026\/07\/IMG_1327.jpeg?resize=300%2C169 300w, https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2026\/07\/IMG_1327.jpeg?resize=1024%2C576 1024w, https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2026\/07\/IMG_1327.jpeg?resize=768%2C432 768w, https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2026\/07\/IMG_1327.jpeg?resize=533%2C300 533w, https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2026\/07\/IMG_1327.jpeg?w=1080 1080w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>O porta-voz do Minist\u00e9rio das Rela\u00e7\u00f5es Exteriores da China, Lin Jian, anunciou nesta segunda-feira (13) \u00e0 imprensa que o presidente chin\u00eas, Xi Jinping, participar\u00e1 da Confer\u00eancia Mundial de IA 2026 e far\u00e1 o discurso principal do evento.<!--more--><\/p>\n<p>Segundo Lin, a Confer\u00eancia Mundial de Intelig\u00eancia Artificial (IA) 2026 e a Reuni\u00e3o de Alto N\u00edvel sobre Governan\u00e7a Global de IA ser\u00e3o realizadas em Shanghai, de 17 a 20 de julho. O tema principal do encontro \u00e9 \u201cParceiros inteligentes, construindo juntos o futuro\u201d.<\/p>\n<p>Lin revelou que a parte chinesa j\u00e1 convidou representantes de governos de diversos pa\u00edses, especialistas dos setores industrial, acad\u00eamico e de pesquisa, al\u00e9m de dirigentes de organiza\u00e7\u00f5es internacionais, para participarem do evento.<\/p>\n<p>\u201cEsperamos aproveitar esta oportunidade para estabelecer uma plataforma que permita ampliar a confian\u00e7a m\u00fatua, construir consensos e aprofundar a coopera\u00e7\u00e3o entre todas as partes, promovendo conjuntamente o desenvolvimento saud\u00e1vel, seguro e ordenado da IA\u201d, concluiu o porta-voz.<\/p>\n<p>Fonte: CMG<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O porta-voz do Minist\u00e9rio das Rela\u00e7\u00f5es Exteriores da China, Lin Jian, anunciou nesta segunda-feira (13) \u00e0 imprensa que o presidente chin\u00eas, Xi Jinping, participar\u00e1 da Confer\u00eancia Mundial de IA 2026 e far\u00e1 o discurso principal do evento.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-39206","post","type-post","status-publish","format-standard","hentry","category-notas"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p7wKYW-acm","jetpack-related-posts":[],"_links":{"self":[{"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/posts\/39206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/comments?post=39206"}],"version-history":[{"count":1,"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/posts\/39206\/revisions"}],"predecessor-version":[{"id":39208,"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/posts\/39206\/revisions\/39208"}],"wp:attachment":[{"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/media?parent=39206"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/categories?post=39206"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/tags?post=39206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}