{"id":8003,"date":"2017-01-28T11:39:37","date_gmt":"2017-01-28T15:39:37","guid":{"rendered":"http:\/\/blogdalucianaoliveira.com.br\/blog\/?p=8003"},"modified":"2017-01-28T11:39:37","modified_gmt":"2017-01-28T15:39:37","slug":"sindsefro-denuncia-o-brasil-na-corte-interamericana-de-direitos-humanos","status":"publish","type":"post","link":"http:\/\/blogdalucianaoliveira.com.br\/blog\/2017\/01\/28\/sindsefro-denuncia-o-brasil-na-corte-interamericana-de-direitos-humanos\/","title":{"rendered":"Sindsef\/RO denuncia o Brasil na Corte Interamericana de Direitos Humanos"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"8004\" data-permalink=\"http:\/\/blogdalucianaoliveira.com.br\/blog\/2017\/01\/28\/sindsefro-denuncia-o-brasil-na-corte-interamericana-de-direitos-humanos\/ddt_1\/\" data-orig-file=\"https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2017\/01\/DDT_1.jpg?fit=660%2C330\" data-orig-size=\"660,330\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"DDT_1\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2017\/01\/DDT_1.jpg?fit=300%2C150\" data-large-file=\"https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2017\/01\/DDT_1.jpg?fit=600%2C300\" src=\"https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2017\/01\/DDT_1.jpg?resize=600%2C300\" alt=\"DDT_1\" width=\"600\" height=\"300\" class=\"alignnone size-full wp-image-8004\" srcset=\"https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2017\/01\/DDT_1.jpg?w=660 660w, https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2017\/01\/DDT_1.jpg?resize=300%2C150 300w, https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2017\/01\/DDT_1.jpg?resize=600%2C300 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>O DDT-Dicloro Difenil Tricloroetano, \u00e9 um produto qu\u00edmico altamente t\u00f3xico utilizado largamente na agricultura e no combate a vetores de endemias (mosquitos causadores de febre amarela, mal\u00e1ria, etc), principalmente nos pa\u00edses tropicais, na Am\u00e9rica do Sul, \u00c1frica e \u00c1sia.<!--more--><\/p>\n<p>Devido ao reconhecido potencial nocivo ao meio ambiente e \u00e0s pessoas que com ele tem contato, o DDT foi banido a mais de sessenta anos na Europa e nos Estados Unidos, permanecendo seu uso no Brasil, principalmente em Rond\u00f4nia, at\u00e9 1992, utilizado em larga escala principalmente no Norte e Centro-Oeste do Brasil, com destaque aos Estados do Acre, Par\u00e1, Rond\u00f4nia, Mato Groso e Goi\u00e1s, sem nenhum tipo de cuidado e instru\u00e7\u00f5es para proteger os trabalhadores que o manuseavam e \u00e0 popula\u00e7\u00e3o que com ele tinham contato.<\/p>\n<p>A desinforma\u00e7\u00e3o era tamanha que os pr\u00f3prios &#8220;guardas da Sucam&#8221; ou &#8220;malaieios&#8221;, como eram chamados os agentes de endemias, utilizavam para armazenar \u00e1gua para o preparo da alimenta\u00e7\u00e3o di\u00e1ria o mesmo balde que era utilizado para preparar o DDT para borrifar as casas dos colonos, que estavam iniciando suas vidas nas in\u00f3spitas regi\u00f5es do Brasil..<\/p>\n<p>A vida era assim. Todos os dias, durante d\u00e9cadas, passavam DDT nas casas e barracos e consumiam o mesmo produto junto com a alimenta\u00e7\u00e3o di\u00e1ria. Um desastre total, em que milhares j\u00e1 foram mortos por essa causa est\u00fapida.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"8005\" data-permalink=\"http:\/\/blogdalucianaoliveira.com.br\/blog\/2017\/01\/28\/sindsefro-denuncia-o-brasil-na-corte-interamericana-de-direitos-humanos\/ddt1\/\" data-orig-file=\"https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2017\/01\/ddt1.jpg?fit=660%2C330\" data-orig-size=\"660,330\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"ddt1\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2017\/01\/ddt1.jpg?fit=300%2C150\" data-large-file=\"https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2017\/01\/ddt1.jpg?fit=600%2C300\" src=\"https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2017\/01\/ddt1.jpg?resize=600%2C300\" alt=\"ddt1\" width=\"600\" height=\"300\" class=\"alignnone size-full wp-image-8005\" srcset=\"https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2017\/01\/ddt1.jpg?w=660 660w, https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2017\/01\/ddt1.jpg?resize=300%2C150 300w, https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2017\/01\/ddt1.jpg?resize=600%2C300 600w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>Al\u00e9m dos agentes de endemias, que tinham contato di\u00e1rio com o DDT, seus familiares tamb\u00e9m foram v\u00edtimas, pois as roupas ensopadas durante o dia ou mesmo semana de trabalho, muitas vezes, eram lavadas na resid\u00eancia dos &#8220;malaieiros&#8221;, contaminando suas esposas e filhos. Um verdadeiro desastre. Total des\u00eddia do Governo Federal.<\/p>\n<p>O DDT foi banido definitivamente do Brasil em 2009, atrav\u00e9s da Lei 11.936\/2009, de iniciativa do ent\u00e3o senador e m\u00e9dico Ti\u00e3o Viana, hoje governador do Acre. O Congresso Nacional reconheceu que o nefasto produto era altamente prejudicial ao meio ambiente, causando &#8220;danos \u00e0s plantas e aos animais, ao meio ambiente&#8221;, mas silencia quanto ao tratamento daqueles intoxicados pelo seu manuseio de forma inadequada, por neglig\u00eancia da Uni\u00e3o.<\/p>\n<p>O Congresso Nacional brasileiro tem demonstrado preocupa\u00e7\u00e3o com o caso, com v\u00e1rias iniciativas legislativas para ajudar aos &#8220;malaieiros&#8221;, infelizmente todas, at\u00e9 agora, in\u00f3cuas. H\u00e1, inclusive, um Projeto de Emenda \u00e0 Constitui\u00e7\u00e3o, a PEC 17\/2014, produzida pelo Sindsef\/RO e apresentada no Senado pelo senador Valdir Raupp (PMDB\/RO), que se encontra na Comiss\u00e3o de Constitui\u00e7\u00e3o e Justi\u00e7a do Senado Federal, com pedido de vistas do senador Alu\u00edzio Nunes Ferreira (PSDB\/SP), l\u00edder do governo federal no Senado.<\/p>\n<p>Diante da observa\u00e7\u00e3o do sofrimento e mortes precoces no meio dos trabalhadores p\u00fablicos que trabalharam com o DDT, foi iniciado um movimento para a promo\u00e7\u00e3o do tratamento \u00e0 sa\u00fade e indeniza\u00e7\u00e3o dos prejudicados pela neglig\u00eancia do governo brasileiro, dos quais o Sindsef\/RO \u00e9 um dos principais sindicatos do Brasil na defesa dessa nobre causa, junto com as entidades cong\u00eaneres do Acre, Par\u00e1, Mato Grosso, Goi\u00e1s, etc.<\/p>\n<p>Dentre as in\u00fameras a\u00e7\u00f5es concretas para denunciar a situa\u00e7\u00e3o e exigir tratamento m\u00e9dico aos prejudicados o Sindsef\/RO \u00e9, at\u00e9 o presente, o \u00fanico sindicato ou entidade do g\u00eanero no pa\u00eds a custear totalmente os exames de sangue para identificar a presen\u00e7a do DDT no organismo dos trabalhadores doentes.<\/p>\n<p>Mais de oitenta por cento desses exames deram positivos. Todos viraram a\u00e7\u00f5es judiciais que se arrastam a d\u00e9cadas, ora na Justi\u00e7a Federal, ora na Justi\u00e7a do Trabalho. Pouqu\u00edssimos servidores conseguiram ser tratados por determina\u00e7\u00e3o judicial, embora existam muitas decis\u00f5es nesse sentido. A Uni\u00e3o recorre das decis\u00f5es e suspende o cumprimento das ordens judiciais.<\/p>\n<p>Os servidores intoxicados est\u00e3o morrendo \u00e0 merc\u00ea da pr\u00f3pria sorte. O Estado brasileiro nada fez. Nada faz.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"8006\" data-permalink=\"http:\/\/blogdalucianaoliveira.com.br\/blog\/2017\/01\/28\/sindsefro-denuncia-o-brasil-na-corte-interamericana-de-direitos-humanos\/ddt-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2017\/01\/DDT-2.jpg?fit=660%2C420\" data-orig-size=\"660,420\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"DDT 2\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2017\/01\/DDT-2.jpg?fit=300%2C191\" data-large-file=\"https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2017\/01\/DDT-2.jpg?fit=600%2C382\" src=\"https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2017\/01\/DDT-2.jpg?resize=600%2C382\" alt=\"DDT 2\" width=\"600\" height=\"382\" class=\"alignnone size-full wp-image-8006\" srcset=\"https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2017\/01\/DDT-2.jpg?w=660 660w, https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2017\/01\/DDT-2.jpg?resize=300%2C191 300w, https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2017\/01\/DDT-2.jpg?resize=471%2C300 471w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>Al\u00e9m de custear exames e promover a\u00e7\u00f5es judiciais, eventos, como audi\u00eancias p\u00fablicas em Assembleias Legislativa, no Congresso Nacional, den\u00fancias na Secretaria de Direitos Humanos da Presid\u00eancia da Rep\u00fablica do Brasil, devido \u00e0 inexist\u00eancia de providencias adequadas ao caso, principalmente no tocante \u00e0 sa\u00fade dos &#8220;malaieiros&#8221; e seus dependentes, o Sindsef\/RO passou a defender a den\u00fancia do Brasil em f\u00f3runs internacionais, como a Organiza\u00e7\u00e3o Internacional do Trabalho \u2013 OIT, a Organiza\u00e7\u00e3o dos Estados Americanos \u2013 OEA, culminando agora em levar o caso para a Corte Interamericana de Direitos Humanos, com sede em S\u00e3o Jos\u00e9, na Costa Rica, pa\u00eds da Am\u00e9rica Central, \u00f3rg\u00e3o judicial aut\u00f4nomo e supranacional, composto por sete ju\u00edzes de origens diversas dentre magistrados de carreira dos pa\u00edses membros, sendo presidido atualmente pelo brasileiro Roberto de Figueiredo Caldas.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"8007\" data-permalink=\"http:\/\/blogdalucianaoliveira.com.br\/blog\/2017\/01\/28\/sindsefro-denuncia-o-brasil-na-corte-interamericana-de-direitos-humanos\/ddt-3\/\" data-orig-file=\"https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2017\/01\/DDT-3.jpg?fit=660%2C420\" data-orig-size=\"660,420\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"DDT 3\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2017\/01\/DDT-3.jpg?fit=300%2C191\" data-large-file=\"https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2017\/01\/DDT-3.jpg?fit=600%2C382\" src=\"https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2017\/01\/DDT-3.jpg?resize=600%2C382\" alt=\"DDT 3\" width=\"600\" height=\"382\" class=\"alignnone size-full wp-image-8007\" srcset=\"https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2017\/01\/DDT-3.jpg?w=660 660w, https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2017\/01\/DDT-3.jpg?resize=300%2C191 300w, https:\/\/i0.wp.com\/blogdalucianaoliveira.com.br\/blog\/wp-content\/uploads\/2017\/01\/DDT-3.jpg?resize=471%2C300 471w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>O objetivo do Sindsef\/RO com essa iniciativa \u00e9 buscar a promo\u00e7\u00e3o de um debate internacional sobre o uso inadequado do DDT e for\u00e7ar o governo brasileiro a promover o tratamento da sa\u00fade e indenizar todos os servidores prejudicados e seus familiares.<\/p>\n<p>Texto de Daniel Pereira, advogado, vice-governador de Rond\u00f4nia e atual presidente do Sindsef\/RO \u2013 Sindicato dos Servidores Federais no Estado de Rond\u00f4nia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O DDT-Dicloro Difenil Tricloroetano, \u00e9 um produto qu\u00edmico altamente t\u00f3xico utilizado largamente na agricultura e no combate a vetores de endemias (mosquitos causadores de febre amarela, mal\u00e1ria, etc), principalmente nos pa\u00edses tropicais, na Am\u00e9rica do Sul, \u00c1frica e \u00c1sia.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-8003","post","type-post","status-publish","format-standard","hentry","category-notas"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p7wKYW-255","jetpack-related-posts":[],"_links":{"self":[{"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/posts\/8003","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/comments?post=8003"}],"version-history":[{"count":1,"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/posts\/8003\/revisions"}],"predecessor-version":[{"id":8008,"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/posts\/8003\/revisions\/8008"}],"wp:attachment":[{"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/media?parent=8003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/categories?post=8003"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/blogdalucianaoliveira.com.br\/blog\/wp-json\/wp\/v2\/tags?post=8003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}